{"id":64207,"date":"2023-03-07T10:02:38","date_gmt":"2023-03-07T09:02:38","guid":{"rendered":"https:\/\/kizeoformscom.kinsta.cloud\/?p=64207"},"modified":"2024-04-09T12:05:10","modified_gmt":"2024-04-09T10:05:10","slug":"mantenimiento-edificios-equans","status":"publish","type":"post","link":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/","title":{"rendered":"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3"},"content":{"rendered":"<p><img decoding=\"async\" class=\"wp-image-117172 size-medium alignleft\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/11\/EQUANS_Blocmarque_RGB-300x114.png\" alt=\"\" width=\"300\" height=\"114\" srcset=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/11\/EQUANS_Blocmarque_RGB-300x114.png 300w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/11\/EQUANS_Blocmarque_RGB-768x292.png 768w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/11\/EQUANS_Blocmarque_RGB.png 968w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<ul>\n<li><strong>Industria:<\/strong> <em><span style=\"font-weight: 400;\">Facility Management<\/span><\/em><\/li>\n<li><strong>Servicios<\/strong>: mantenimiento integral y auditor\u00edas de eficiencia energ\u00e9tica<\/li>\n<li><strong>N\u00famero de empleados<\/strong>: 2.000<\/li>\n<\/ul>\n<blockquote><p><b>El desaf\u00edo:<\/b> Obtener informaci\u00f3n in situ de diversas instalaciones a nivel nacional.<\/p><\/blockquote>\n<blockquote><p><b>El beneficio:<\/b> Centralizar la informaci\u00f3n de todos los proyectos en Kizeo Forms, automatizar el mantenimiento de edificios y ahorrar tiempo administrativo.<\/p><\/blockquote>\n<blockquote><p><b>Entrevistados de Equan Chile: <\/b>Allyson Gonz\u00e1lez, subgerenta de excelencia operacional; Francisco Vargas, especialista en mantenimiento y confiabilidad; Jhon P\u00e9rez, jefe de mantenimiento y confiabilidad; y Nehem\u00edas Tirado, jefe de <span style=\"font-weight: 400;\">operaciones.<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Para lograr automatizar el mantenimiento de edificios, Equans Chile, apost\u00f3 por una<a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/software-de-mantenimiento\/\" target=\"_blank\" rel=\"noopener\"> herramienta digital de mantenimiento<\/a> que les permitiera<\/span><b> ahorrar tiempo administrativo <\/b><span style=\"font-weight: 400;\">y reforzar la fiabilidad de sus procesos internos. Gracias a esto, la gesti\u00f3n del d\u00eda a d\u00eda se ha transformado desde que cuentan con una app.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Visitamos sus instalaciones en Santiago de Chile para conocer de primera mano su experiencia y para entender<\/span><b> c\u00f3mo han reforzado su plan de mantenimiento.<\/b><span style=\"font-weight: 400;\"> Nos contaron c\u00f3mo el trabajo en terreno de los t\u00e9cnicos ha mejorado y, en consecuencia, han conseguido fortalecer la calidad de atenci\u00f3n a sus clientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0En este <\/span><b>video testimonio<\/b><span style=\"font-weight: 400;\"> nuestros entrevistados nos cuentan c\u00f3mo la digitalizaci\u00f3n facilit\u00f3 el mantenimiento de edificios y ha permitido automatizar la gesti\u00f3n del trabajo en terreno: <\/span><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/m02FU7RbjJI\" width=\"720\" height=\"405\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #55C96B;\">La empresa, l\u00edderes en el facility management<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00bfTe gustar\u00eda que te cont\u00e1ramos m\u00e1s sobre Equans Chile? \u00a1Pues vamos a ello! Esta empresa est\u00e1 <\/span><b>especializada en el mantenimiento multit\u00e9cnico <\/b><span style=\"font-weight: 400;\">y desarrollan su actividad a lo largo de Am\u00e9rica Latina (Chile, Per\u00fa, Colombia, M\u00e9xico y Brasil) y tambi\u00e9n tienen presencia en Europa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su actividad, abarcan el mantenimiento integral y cuentan con <\/span><b>m\u00e1s de dos mil t\u00e9cnicos en terreno<\/b><span style=\"font-weight: 400;\"> en Chile que trabajan en distintos sectores:<\/span><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/field-service-management-software-app\/\"> <span style=\"font-weight: 400;\">facility management<\/span><\/a><span style=\"font-weight: 400;\">, miner\u00eda, energ\u00eda, entre otros. Hacen mantenimientos de climatizaci\u00f3n, electricidad, fontaner\u00eda, iluminaci\u00f3n, grupos electr\u00f3genos y tableros de media y baja tensi\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para comprender mejor la empresa y <\/span><b>conocer c\u00f3mo han logrado automatizar el mantenimiento de edificios<\/b><span style=\"font-weight: 400;\">, tuvimos la suerte de hablar con cuatro miembros clave del equipo: Allyson Gonz\u00e1lez, subgerente de excelencia operacional; Francisco Vargas, especialista en mantenimiento y confiabilidad; Jhon P\u00e9rez, jefe de mantenimiento y confiabilidad; y Nehem\u00edas Tirado, jefe de operaciones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a1Sigue leyendo para entender c\u00f3mo han automatizado esta gesti\u00f3n!<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #55C96B;\">La necesidad: conseguir que el mantenimiento de edificios sea m\u00e1s eficaz<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Hoy en d\u00eda, Equans Chile, adem\u00e1s de diversas ramas de acci\u00f3n, est\u00e1 a cargo del facility management de una cadena de centros comerciales. Son responsables de realizar diversas tareas de mantenimiento, entre las que se encuentran la revisi\u00f3n del sistema de agua, grupos electr\u00f3genos, elementos verticales, equipos el\u00e9ctricos y de climatizaci\u00f3n.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Francisco Vargas, especialista en Mantenimiento y Confiabilidad, explica que el proceso de digitalizaci\u00f3n nace de la necesidad de <\/span><b>obtener informaci\u00f3n para la toma de decisiones<\/b><span style=\"font-weight: 400;\"> en tiempo real de muchas de estas instalaciones a nivel nacional: \u201cten\u00edamos t\u00e9cnicos en todo Chile y necesit\u00e1bamos centralizar la informaci\u00f3n\u201d, explica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Antiguamente, trabajaban con partes de trabajo en papel que los t\u00e9cnicos diligenciaban y luego era el supervisor quien deb\u00eda digitalizarlas. La gerencia de Equans en Francia <\/span><b>les recomend\u00f3 implementar Kizeo Forms <\/b><span style=\"font-weight: 400;\">en sus operaciones por los buenos resultados que ellos hab\u00edan logrado. <\/span><\/p>\n<div>\n<div style=\"border-radius: 1.3em; padding: 3%; background: rgba(33, 33, 33, 0.05);\">\n<p><span style=\"font-weight: 400;\">Tal vez te gustar\u00eda saber m\u00e1s sobre una <\/span><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/por-que-debo-usar-una-app-para-mantenimiento-industrial\/\"><span style=\"font-weight: 400;\">app para mantenimiento industrial<\/span><\/a><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2><span style=\"color: #55C96B;\">La soluci\u00f3n: digitalizar formularios para gestionar el mantenimiento de edificios<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Comenzaron a trabajar con Kizeo Forms y el \u00e9xito de la digitalizaci\u00f3n completa no tard\u00f3 en llegar. La transici\u00f3n de papel a digital cambi\u00f3 completamente el trabajo de la empresa, <\/span><b>produciendo una digitalizaci\u00f3n completa de los procesos<\/b><span style=\"font-weight: 400;\">. Varga cuenta que, desde que trabajan con Kizeo Forms, \u201csomos una empresa digital: no trabajamos con papeles. No trabajamos a la antigua\u201d afirma.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Crearon una conexi\u00f3n con su ERP Planon, donde se generan las \u00f3rdenes de trabajo, que son autom\u00e1ticamente enviadas a Kizeo Forms. Cuando un t\u00e9cnico realiza la intervenci\u00f3n en terreno y manda el dato a trav\u00e9s de Kizeo Forms con el n\u00famero de la orden de trabajo, autom\u00e1ticamente se cierra la orden de trabajo en Planon. As\u00ed <\/span><b>tienen un control total de sus operaciones.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Francisco Vargas y Jhon Perez crean formularios constantemente para cubrir las necesidades que se presentan a diario.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cKizeo Forms se usa a diario para todo. Es la biblia de la empresa. Esto se debe a que realizamos todo el trabajo en terreno, con mucha demanda de mantenimientos\u201d.<\/span><\/p>\n<p style=\"text-align: right;\"><em><span style=\"font-weight: 400;\">Francisco Vargas, especialista en mantenimiento y confiabilidad en Equans Chile<\/span><\/em><\/p>\n<\/blockquote>\n<h3>\u00bfC\u00f3mo gestionan el plan de mantenimiento de edificios?<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-314629 aligncenter\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-equans-300x164.png\" alt=\"mantenimiento de edificios equans\" width=\"849\" height=\"464\" srcset=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-equans-300x164.png 300w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-equans-1024x561.png 1024w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-equans-768x421.png 768w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-equans.png 1512w\" sizes=\"(max-width: 849px) 100vw, 849px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">El personal de mantenimiento, en terreno,<\/span><b> debe recoger datos y realizar reportes<\/b><span style=\"font-weight: 400;\"> de <a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-preventivo\/\" target=\"_blank\" rel=\"noopener\">mantenimiento preventivo<\/a>, de aver\u00edas y revisiones rutinarias. Desde que cuentan con una app de mantenimiento, la forma en que trabajan ha cambiado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Han conseguido automatizar las acciones de mantenimiento de edificios programando las intervenciones, <\/span><b>mejorando el tiempo de respuesta<\/b><span style=\"font-weight: 400;\"> ante<\/span><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/como-realizar-mantenimiento-correctivo\/\"> <span style=\"font-weight: 400;\">mantenimientos correctivos<\/span><\/a><span style=\"font-weight: 400;\"> e integrando sus reportes, de forma instant\u00e1nea, con la plataforma SAP del cliente.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cNuestros t\u00e9cnicos pueden saber si la actividad es reiterativa y requiere desarrollarse en un bloque mayor a un d\u00eda. Pueden ver la notificaci\u00f3n anterior y saber lo que sucedi\u00f3 y, por ende, pueden tomar acciones y decisiones respecto a esa informaci\u00f3n\u201d.\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><em><span style=\"font-weight: 400;\">Jhon P\u00e9rez, jefe de mantenimiento y confiabilidad<\/span><\/em><\/p>\n<\/blockquote>\n<h4>Caso pr\u00e1ctico, \u00bfc\u00f3mo usan la app para el mantenimiento de edificios en el d\u00eda a d\u00eda?<\/h4>\n<p><span style=\"font-weight: 400;\">La clave est\u00e1 en contar con una app que, a trav\u00e9s de formularios digitales, permite automatizar la gesti\u00f3n del<\/span><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-preventivo-calidad\"><span style=\"font-weight: 400;\"> mantenimiento preventivo<\/span><\/a><span style=\"font-weight: 400;\"> y correctivo de edificios. Por ejemplo, para Nehem\u00edas Tirado, jefe de operaciones, y Jhon P\u00e9rez, jefe de mantenimiento y confiabilidad, uno de los proyectos m\u00e1s exitosos fue el de la<\/span><b> implementaci\u00f3n de un formulario para termograf\u00eda de tableros el\u00e9ctricos<\/b><span style=\"font-weight: 400;\">. Lo hicieron en octubre de 2018. Esto les permite digitalizar la informaci\u00f3n de muchos sitios a nivel nacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los t\u00e9cnicos pueden realizar la intervenci\u00f3n rutinaria, recoger los datos y actualizar el status. Esto hace que la informaci\u00f3n quede actualizada y disponible en el sistema SAP del cliente. <\/span><b>No hay p\u00e9rdida de informaci\u00f3n<\/b><span style=\"font-weight: 400;\"> ni hay que malgastar tiempo en la transcripci\u00f3n de los datos.\u00a0<\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-314636 aligncenter\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-300x157.png\" alt=\"mantenimiento de edificios\" width=\"864\" height=\"452\" srcset=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-300x157.png 300w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-1024x535.png 1024w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-768x401.png 768w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios-1536x802.png 1536w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/mantenimiento-de-edificios.png 1588w\" sizes=\"(max-width: 864px) 100vw, 864px\" \/><\/p>\n<div>\n<div style=\"border-radius: 1.3em; padding: 3%; background: rgba(33, 33, 33, 0.05);\">\n<p><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/software-sat\/\"><span style=\"font-weight: 400;\">\u00bfNecesitas un software sat?<\/span><\/a><span style=\"font-weight: 400;\"> Te contamos c\u00f3mo elegir el adecuado<\/span><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #55C96B;\">Kizeo Forms para facility management en retail<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Kizeo Forms es una potente herramienta para las empresas que se dedican al facility management para empresas del sector retail. Para el retail, poder ofrecer el <\/span><b>mejor servicio y mayor grado de calidad es muy importante.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por esto, realizar intervenciones de facility management eficientes y muy profesionales es lo que marca la diferencia. Esto ayuda a garantizar la retenci\u00f3n y fidelizaci\u00f3n del cliente final.\u00a0<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u201cNosotros hacemos gesti\u00f3n de mantenimiento y confiabilidad y la confiabilidad depende mucho de los datos que nosotros podamos obtener de las plataformas que utilizamos\u201d.\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><em><span style=\"font-weight: 400;\">Allyson Gonz\u00e1lez, subgerenta de excelencia operacional en Equans Chile<\/span><\/em><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Contar con un software para <\/span><b>controlar la gesti\u00f3n de mantenimientos a edificios<\/b><span style=\"font-weight: 400;\"> de centros comerciales permite dar respuesta m\u00e1s r\u00e1pida a cualquier imprevisto, llevar un registro adecuado de todos los mantenimientos hechos y evita incidencias que afecten la reputaci\u00f3n del establecimiento.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div style=\"border-radius: 1.3em; padding: 3%; background: rgba(33, 33, 33, 0.05);\">\n<p style=\"text-align: center; font-size: 16px;\"><strong>Quiz\u00e1s te interese:<a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-preventivo\/\" target=\"_blank\" rel=\"noopener\"> Maximiza la eficiencia del mantenimiento preventivo<\/a><\/strong><\/p>\n<\/div>\n<h3><\/h3>\n<h3>Funcionalidades preferidas de Kizeo Forms para los t\u00e9cnicos de mantenimiento<\/h3>\n<p><span style=\"font-weight: 400;\">La curva de aprendizaje y la apropiaci\u00f3n de Kizeo Forms ha dado frutos tangibles en tres a\u00f1os de uso. En un principio contaban con formularios muy complejos y con muchos campos. Ahora, han logrado reducir la complejidad de los mismo al<\/span><b> crear formularios m\u00e1s cortos que transfieren informaci\u00f3n a otros formularios<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfQu\u00e9 funcionalidades les han permitido ganar en automatizaci\u00f3n y simplicidad?:<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"vertical-align: inherit;\"><div class=\"su-row\"> <div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/caracteristicas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-57981\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2019\/10\/Disen\u0303o-sin-ti\u0301tulo-3-300x186.png\" alt=\"\" width=\"300\" height=\"186\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"vertical-align: inherit;\">Tener la informaci\u00f3n prerellenada con las listas externas<br \/>\n<\/div><\/div> <\/span><span style=\"vertical-align: inherit;\"><div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-57989\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2019\/10\/check-300x186.png\" alt=\"\" width=\"300\" height=\"186\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"vertical-align: inherit;\">Realizar intervenciones m\u00e1s cortas gracias al uso de los check box <\/div><\/div> <div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-57996\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2019\/10\/3-300x186.png\" alt=\"\" width=\"300\" height=\"186\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"vertical-align: inherit;\">Centralizar toda la documentaci\u00f3n en la plataforma web <\/div><\/div> <div class=\"su-column su-column-size-1-4\"><div class=\"su-column-inner su-u-clearfix su-u-trim\"><\/span><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58003\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2019\/10\/reporte-300x186.png\" alt=\"\" width=\"300\" height=\"186\" \/><\/p>\n<p style=\"text-align: center;\">Lograr supervisar el desempe\u00f1o del equipo con reportes autom\u00e1ticos<\/p>\n<p style=\"text-align: center;\"><span style=\"vertical-align: inherit;\">\u00a0<\/div><\/div> <\/div><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/signup.kizeo.com\/es-es\/prueba-gratis-kizeo-forms?lang=es&#038;_ga=2.41708384.354311670.1528702534-1856606514.1505219016\" class=\"su-button su-button-style-3d\" style=\"color:#FFFFFF;background-color:#55C96B;border-color:#44a156;border-radius:77px\" target=\"_blank\" rel=\"noopener noreferrer\" title=\"!Empiece ya!\"><span style=\"color:#FFFFFF;padding:0px 34px;font-size:25px;line-height:50px;border-color:#88da98;border-radius:77px;text-shadow:none\"> \u00a1Prueba gratis 15 d\u00edas!<\/span><\/a>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><!-- DEBUT DU CODE EDIT --><\/p>\n<div id=\"wrap\">\n<div id=\"container\" class=\"hvr-grow\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-315139 \" title=\"control de obra\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/OP-services-300x159.png\" alt=\"\" width=\"766\" height=\"406\" srcset=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/OP-services-300x159.png 300w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/OP-services.png 751w\" sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/p>\n<div id=\"text\">\n<p id=\"title\" style=\"font-weight: bold; font-size: 1.7em; color: #55C96B;\">Caso de \u00e9xito \u2013 OP Service digitaliza sus informes de mantenimiento el\u00e9ctrico<\/p>\n<p id=\"extract\">Miguel \u00c1ngel Vilchez, gerente general de OP Service, nos cuenta c\u00f3mo han logrado digitalizar los informes de mantenimiento. Hablamos sobre c\u00f3mo lograr una mayor liquidez de caja y la trayectoria de la empresa en Per\u00fa.<\/p>\n<p><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/caso-de-exito-op-service-digitaliza-informes-mantenimiento-electrico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Leer caso de de \u00e9xito sobre mantenimiento el\u00e9ctrico<\/a><\/p>\n<\/div>\n<\/div>\n<div id=\"container\" class=\"hvr-grow\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-315146 \" title=\"control de obra\" src=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/andes-facilitys-300x159.png\" alt=\"\" width=\"785\" height=\"416\" srcset=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/andes-facilitys-300x159.png 300w, https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2020\/12\/andes-facilitys.png 751w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/><\/p>\n<div id=\"text\">\n<p id=\"title\" style=\"font-weight: bold; font-size: 1.7em; color: #55C96B;\"><strong>La digitalizaci\u00f3n de empresas de mantenimiento<\/strong><\/p>\n<p id=\"extract\">Andes Facility buscaba garantizar la trazabilidad de los reportes de mantenimiento preventivo. Al realizarlos en papel, los t\u00e9cnicos consum\u00edan un valioso tiempo y la informaci\u00f3n tardaba en llegar al cliente.<\/p>\n<p><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/la-digitalizacion-de-empresas-de-mantenimiento\/\" target=\"_blank\" rel=\"noopener noreferrer\">Leer sobre la digitalizaci\u00f3n de empresas de mantenimiento<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<style> #wrap {display: flex; margin-top: 75px; margin-bottom: 50px; justify-content: center;} #container { width: 45%; margin-right: 2.5%; box-shadow: 1px 1px 12px #555; border-radius: 5px;} #img { border-radius: 5px 5px 0px 0px;} #text { padding: 0px 20px 20px 20px; } #date { text-align: right; } #title { font-weight: bold; font-size: 1.7em; color: #55C96B !important;} #readmore { padding: 5px 10px 5px 10px; background-color: #55C96B !important; color: #FFFFFF !important; border-radius: 5px; user-select: none;} \/* Grow animation *\/ .hvr-grow { display: inline-block; vertical-align: middle; -webkit-transform: perspective(1px) translateZ(0); transform: perspective(1px) translateZ(0); box-shadow: 0 0 1px rgba(0, 0, 0, 0); -webkit-transition-duration: 0.3s; transition-duration: 0.3s; -webkit-transition-property: transform; transition-property: transform;} .hvr-grow:hover, .hvr-grow:focus, .hvr-grow:active { -webkit-transform: scale(1.05); transform: scale(1.05);} #date-responsive { display: none; text-align: right; } @media screen and (max-width: 800px) { #wrap {display: block;} #container { width: 100%; margin-right: 0; margin-bottom: 20px;} #img {display: none;} #date-responsive {display: block;} #date {display: none;} } <\/style>\n","protected":false},"excerpt":{"rendered":"<p>Industria: Facility Management Servicios: mantenimiento integral y auditor\u00edas de eficiencia energ\u00e9tica N\u00famero de empleados: 2.000 El desaf\u00edo: Obtener informaci\u00f3n in situ de diversas instalaciones a nivel nacional. El beneficio: Centralizar la informaci\u00f3n de todos los proyectos en Kizeo Forms, automatizar el mantenimiento de edificios y ahorrar tiempo administrativo. Entrevistados de Equan Chile: Allyson Gonz\u00e1lez, subgerenta de excelencia operacional; Francisco Vargas, especialista en mantenimiento y confiabilidad; [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":314646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[44],"tags":[615,616,229],"class_list":["post-64207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testimonios-de-clientes","tag-aplicacion-para-facility-managament","tag-facility-managament","tag-mantenimiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3<\/title>\n<meta name=\"description\" content=\"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3\" \/>\n<meta property=\"og:description\" content=\"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/\" \/>\n<meta property=\"og:site_name\" content=\"Kizeo Forms\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-07T09:02:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T10:05:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2289\" \/>\n\t<meta property=\"og:image:height\" content=\"781\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Greilysu Moreno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Greilysu Moreno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/\",\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/\",\"name\":\"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3\",\"isPartOf\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png\",\"datePublished\":\"2023-03-07T09:02:38+00:00\",\"dateModified\":\"2024-04-09T10:05:10+00:00\",\"author\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/b6367021074ad87d9908172faec13817\"},\"description\":\"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.\",\"breadcrumb\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage\",\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png\",\"contentUrl\":\"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png\",\"width\":2289,\"height\":781,\"caption\":\"mantenimiento de edificios equans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/#website\",\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/\",\"name\":\"Kizeo Forms\",\"description\":\"Mobile Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/b6367021074ad87d9908172faec13817\",\"name\":\"Greilysu Moreno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4bef31654d04190c3cb1519f9fdf4c14?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4bef31654d04190c3cb1519f9fdf4c14?s=96&r=g\",\"caption\":\"Greilysu Moreno\"},\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/es\/author\/greily\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3","description":"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3","og_description":"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.","og_url":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/","og_site_name":"Kizeo Forms","article_published_time":"2023-03-07T09:02:38+00:00","article_modified_time":"2024-04-09T10:05:10+00:00","og_image":[{"width":2289,"height":781,"url":"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png","type":"image\/png"}],"author":"Greilysu Moreno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Greilysu Moreno","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/","url":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/","name":"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3","isPartOf":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage"},"image":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage"},"thumbnailUrl":"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png","datePublished":"2023-03-07T09:02:38+00:00","dateModified":"2024-04-09T10:05:10+00:00","author":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/b6367021074ad87d9908172faec13817"},"description":"Implementar una app ha permitido simplificar la gesti\u00f3n del mantenimiento de edificios. Conoce c\u00f3mo Equans ha logrado ahorrar tiempo.","breadcrumb":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#primaryimage","url":"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png","contentUrl":"https:\/\/kizeoformscom.kinsta.cloud\/wp-content\/uploads\/2023\/03\/Testimonio-Equans.png","width":2289,"height":781,"caption":"mantenimiento de edificios equans"},{"@type":"BreadcrumbList","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/mantenimiento-edificios-equans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kizeoformscom.kinsta.cloud\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfAutomatizar el mantenimiento de edificios? Equans lo logr\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/#website","url":"https:\/\/kizeoformscom.kinsta.cloud\/es\/","name":"Kizeo Forms","description":"Mobile Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kizeoformscom.kinsta.cloud\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/b6367021074ad87d9908172faec13817","name":"Greilysu Moreno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kizeoformscom.kinsta.cloud\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4bef31654d04190c3cb1519f9fdf4c14?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bef31654d04190c3cb1519f9fdf4c14?s=96&r=g","caption":"Greilysu Moreno"},"url":"https:\/\/kizeoformscom.kinsta.cloud\/es\/author\/greily\/"}]}},"_links":{"self":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/posts\/64207"}],"collection":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/comments?post=64207"}],"version-history":[{"count":6,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/posts\/64207\/revisions"}],"predecessor-version":[{"id":377409,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/posts\/64207\/revisions\/377409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/media\/314646"}],"wp:attachment":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/media?parent=64207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/categories?post=64207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/es\/wp-json\/wp\/v2\/tags?post=64207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}