{"id":2605,"date":"2016-09-16T13:05:24","date_gmt":"2016-09-16T11:05:24","guid":{"rendered":"http:\/\/kizeoformscom.kinsta.cloud\/fr\/?p=2605"},"modified":"2019-09-11T18:06:19","modified_gmt":"2019-09-11T16:06:19","slug":"utilisation-application-en-details-2","status":"publish","type":"post","link":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/","title":{"rendered":"L\u2019application Kizeo Forms en d\u00e9tails"},"content":{"rendered":"<h3 style=\"text-align: justify;\">Le menu Actualiser.<\/h3>\n<p style=\"text-align: justify;\">Vous pouvez actualiser manuellement vos formulaires afin que tout changement leur ayant \u00e9t\u00e9\u00a0apport\u00e9 (depuis le back office) soit pris en compte.\u00a0L\u2019actualisation se fait \u00e9galement de mani\u00e8re automatique, si la case\u00a0\u00ab\u00a0Actualiser automatiquement les formulaires\u00a0\u00bb est coch\u00e9e dans les options.<\/p>\n<h3 style=\"text-align: justify;\">Le menu Historique.<\/h3>\n<p style=\"text-align: justify;\"><strong>Brouillon<\/strong>\u00a0: c\u2019est l\u00e0 que\u00a0vous trouverez les donn\u00e9es\u00a0que vous avez sauvegard\u00e9es en brouillon, en cliquant sur <strong>Brouillon<\/strong> \u00e0 la fin de votre saisie.<\/p>\n<p style=\"text-align: justify;\"><strong>En attente<\/strong>\u00a0: c\u2019est l\u00e0 que vous trouverez les donn\u00e9es\u00a0qui sont en attente d\u2019envoi. Cela signifie que vous avez saisi des donn\u00e9es\u00a0hors connexion internet, d\u00e8s que le mobile trouvera une connexion de qualit\u00e9, elles\u00a0seront envoy\u00e9es sur le\u00a0serveur.<\/p>\n<p style=\"text-align: justify;\"><strong>Envoy\u00e9s<\/strong>\u00a0: c\u2019est l\u2019historique de vos\u00a0donn\u00e9es enregistr\u00e9es sur le serveur.<\/p>\n<p style=\"text-align: justify;\"><strong>Recherche<\/strong>\u00a0: ici, vous avez la possibilit\u00e9 de retrouver une donn\u00e9e saisie pr\u00e9c\u00e9demment (sans limite de temps) gr\u00e2ce \u00e0 un mot-cl\u00e9 ou une donn\u00e9e pr\u00e9cise de votre formulaire. Pour plus d\u2019informations, lisez notre article\u00a0<a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/fonction-recherche-historique-mobile\/\" target=\"_blank\" rel=\"noopener noreferrer\">Recherche de\u00a0formulaire<\/a>.\u00a0Selon les param\u00e8tres d\u00e9finis par l\u2019administrateur, il est \u00e9galement\u00a0possible de voir les donn\u00e9es\u00a0envoy\u00e9es par les autres utilisateurs.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #55C96B;\">Astuce<\/span> :<\/strong> Dans les onglets <strong>Brouillon<\/strong> et <strong>Envoy\u00e9s<\/strong> vous pouvez supprimer l\u2019historique de votre mobile en cliquant sur le menu (en haut \u00e0 droite) puis sur \u00ab\u00a0Tout supprimer\u00a0\u00bb.<\/p>\n<h3 style=\"text-align: justify;\">Le menu R\u00e9ception.<\/h3>\n<p style=\"text-align: justify;\">Dans <strong>R\u00e9ception<\/strong>, vous trouverez :<\/p>\n<ul style=\"text-align: justify;\">\n<li>Les <a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/le-push\/\" target=\"_blank\" rel=\"noopener noreferrer\">push<\/a> : des donn\u00e9es\u00a0pr\u00e9-remplies envoy\u00e9es par l\u2019administrateur (ordinateur \u00e0 mobile).<\/li>\n<li>Les <a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/transfert-de-donnees-entre-utilisateurs\/\" target=\"_blank\" rel=\"noopener noreferrer\">transferts<\/a> : des donn\u00e9es qui vous ont \u00e9t\u00e9 transf\u00e9r\u00e9es par vos collaborateurs (mobile \u00e0 mobile).<\/li>\n<li>Vous pourrez visualiser les push sur une <a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/visualisation-push-mobile-carte-google-map\/\" target=\"_blank\" rel=\"noopener noreferrer\">carte<\/a>, s\u2019ils contiennent des coordonn\u00e9es de g\u00e9olocalisation.<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\">Le menu Options.<\/h3>\n<p style=\"text-align: justify;\">Ce sont\u00a0les\u00a0options li\u00e9es au comportement sur le\u00a0mobile\u00a0:<\/p>\n<p style=\"text-align: justify;\"><strong>Demander confirmation lors d\u2019un transfert\u00a0<\/strong>\u00a0: lorsque vous transf\u00e9rez un formulaire \u00e0 un utilisateur, Kizeo Forms vous demandera si vous \u00eates certain de vouloir transf\u00e9rer votre formulaire. Pour en savoir plus sur les transferts entre utilisateurs, lisez notre tutoriel <a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/transfert-de-donnees-entre-utilisateurs\/\" target=\"_blank\" rel=\"noopener noreferrer\">Transfert de donn\u00e9es entre utilisateurs<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Revenir \u00e0 l\u2019\u00e9cran principal apr\u00e8s la saisie d\u2019un formulaire<\/strong>\u00a0: apr\u00e8s avoir saisi et enregistr\u00e9 un formulaire, vous serez redirig\u00e9 vers la page principale de l\u2019application\u00a0: la liste de\u00a0vos formulaires.<\/p>\n<p style=\"text-align: justify;\"><strong>Revenir \u00e0 l\u2019\u00e9cran des r\u00e9ceptions apr\u00e8s la saisie d\u2019un formulaire<\/strong> : apr\u00e8s avoir saisi un push, au lieu de revenir dans l\u2019\u00e9cran des r\u00e9ceptions vous reviendrez sur l\u2019\u00e9cran principal, soit la liste de vos formulaires.<\/p>\n<p style=\"text-align: justify;\"><strong>Actualiser automatiquement les formulaires<\/strong>\u00a0: au d\u00e9marrage de l\u2019application, les formulaires seront actualis\u00e9s de fa\u00e7on automatique et syst\u00e9matique. Seulement les derniers formulaires modifi\u00e9s sont actualis\u00e9s.<\/p>\n<p style=\"text-align: justify;\"><strong>Autoriser l\u2019affichage de plusieurs \u00e9l\u00e9ments par ligne<\/strong>\u00a0: lors de la cr\u00e9ation de votre formulaire, vous pouvez d\u00e9cider de placer des \u00e9l\u00e9ments c\u00f4te \u00e0 c\u00f4te (dans les options avanc\u00e9es de chaque \u00e9l\u00e9ment). Pour que ces \u00e9l\u00e9ments soient affich\u00e9s c\u00f4te \u00e0 c\u00f4te sur votre mobile ou tablette, vous devez activer cette option \u00e9galement. Cette fonction est optionnelle car l\u2019affichage sur mobile et tablette diff\u00e8re selon la taille de l\u2019\u00e9cran.<\/p>\n<p style=\"text-align: justify;\"><strong>Th\u00e8me<\/strong> : ici vous pourrez personnaliser la couleur de votre application selon des th\u00e8mes que nous avons d\u00e9finis. Pour en savoir plus sur la personnalisation de l\u2019application, reportez-vous \u00e0 notre tutoriel <a href=\"\/\/kizeoformscom.kinsta.cloud\/fr\/personnaliser-application-definir-theme-couleur\/\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00e9finir un th\u00e8me de couleur<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>R\u00e9-initialiser les formulaires<\/strong> : en cliquant sur ce bouton vous\u00a0mettez \u00e0 jour tous vos formulaires et listes.\u00a0Si l\u2019application se comporte anormalement c\u2019est une premi\u00e8re possibilit\u00e9 de manipulation.<\/p>\n<h3 style=\"text-align: justify;\">Le menu Information.<\/h3>\n<p style=\"text-align: justify;\">Dans <strong>Information\u00a0<\/strong>vous pourrez lire le num\u00e9ro de\u00a0la version de l\u2019application. Il est important de toujours avoir la derni\u00e8re version de Kizeo Forms afin de b\u00e9n\u00e9ficier de toutes les fonctionnalit\u00e9s de celle-ci.<\/p>\n<hr \/>\n<h3>Pour aller plus loin&#8230;<\/h3>\n<ul>\n<li><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/premiere-utilisation-application\/\" target=\"_blank\" rel=\"noopener noreferrer\">Guide de premi\u00e8re utilisation\u00a0de l\u2019application.<\/a><\/li>\n<li><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/enregistrer-brouillon\/\" target=\"_blank\" rel=\"noopener noreferrer\">Enregistrez vos donn\u00e9es ou cr\u00e9ez un brouillon ?<\/a><\/li>\n<li><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/travailler-sans-connexion-internet-la-force-de-kizeo-forms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Le mode hors-ligne.<\/a><\/li>\n<li><a href=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/fonction-recherche-historique-mobile\/\" target=\"_blank\" rel=\"noopener noreferrer\">Recherchez une donn\u00e9e saisie.<\/a><\/li>\n<\/ul>\n<hr \/>\n<div class=\"shortcode-block-quote-center\">\n<blockquote>\n<p style=\"text-align: justify;\"><span style=\"color: #95c01f;\">N\u2019h\u00e9sitez pas \u00e0 commenter cet article !<\/span><br \/>\nNous sommes disponibles pour r\u00e9pondre \u00e0 vos questions, suggestions, remarques, etc. !<\/p>\n<\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le menu Actualiser. Vous pouvez actualiser manuellement vos formulaires afin que tout changement leur ayant \u00e9t\u00e9\u00a0apport\u00e9 (depuis le back office) soit pris en compte.\u00a0L\u2019actualisation se fait \u00e9galement de mani\u00e8re automatique, si la case\u00a0\u00ab\u00a0Actualiser automatiquement les formulaires\u00a0\u00bb est coch\u00e9e dans les options. Le menu Historique. Brouillon\u00a0: c\u2019est l\u00e0 que\u00a0vous trouverez les donn\u00e9es\u00a0que vous avez sauvegard\u00e9es en brouillon, en cliquant sur Brouillon \u00e0 la fin de votre [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[33],"class_list":["post-2605","post","type-post","status-publish","format-standard","hentry","category-tutoriels","tag-sur-le-mobile"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms<\/title>\n<meta name=\"description\" content=\"Ce tutoriel est destin\u00e9 aux utilisateurs de l&#039;application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms\" \/>\n<meta property=\"og:description\" content=\"Ce tutoriel est destin\u00e9 aux utilisateurs de l&#039;application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Kizeo Forms\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-16T11:05:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-11T16:06:19+00:00\" \/>\n<meta name=\"author\" content=\"Camila Mazas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Camila Mazas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/\",\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/\",\"name\":\"L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms\",\"isPartOf\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#website\"},\"datePublished\":\"2016-09-16T11:05:24+00:00\",\"dateModified\":\"2019-09-11T16:06:19+00:00\",\"author\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/4fa25132949373e93f5d6119cb19ec3a\"},\"description\":\"Ce tutoriel est destin\u00e9 aux utilisateurs de l'application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.\",\"breadcrumb\":{\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019application Kizeo Forms en d\u00e9tails\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#website\",\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/\",\"name\":\"Kizeo Forms\",\"description\":\"Mobile Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/4fa25132949373e93f5d6119cb19ec3a\",\"name\":\"Camila Mazas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bfce2f11f4611fc92a89f597bb2530c2?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bfce2f11f4611fc92a89f597bb2530c2?s=96&r=g\",\"caption\":\"Camila Mazas\"},\"url\":\"https:\/\/kizeoformscom.kinsta.cloud\/fr\/author\/camila\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms","description":"Ce tutoriel est destin\u00e9 aux utilisateurs de l'application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms","og_description":"Ce tutoriel est destin\u00e9 aux utilisateurs de l'application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.","og_url":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/","og_site_name":"Kizeo Forms","article_published_time":"2016-09-16T11:05:24+00:00","article_modified_time":"2019-09-11T16:06:19+00:00","author":"Camila Mazas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Camila Mazas","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/","url":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/","name":"L\u2019application Kizeo Forms en d\u00e9tails - Kizeo Forms","isPartOf":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#website"},"datePublished":"2016-09-16T11:05:24+00:00","dateModified":"2019-09-11T16:06:19+00:00","author":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/4fa25132949373e93f5d6119cb19ec3a"},"description":"Ce tutoriel est destin\u00e9 aux utilisateurs de l'application. Vous ferez un tour complet des fonctionnalit\u00e9s de la partie mobile de Kizeo Forms.","breadcrumb":{"@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/utilisation-application-en-details-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019application Kizeo Forms en d\u00e9tails"}]},{"@type":"WebSite","@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#website","url":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/","name":"Kizeo Forms","description":"Mobile Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/4fa25132949373e93f5d6119cb19ec3a","name":"Camila Mazas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bfce2f11f4611fc92a89f597bb2530c2?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfce2f11f4611fc92a89f597bb2530c2?s=96&r=g","caption":"Camila Mazas"},"url":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/author\/camila\/"}]}},"_links":{"self":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/posts\/2605"}],"collection":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/comments?post=2605"}],"version-history":[{"count":0,"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/posts\/2605\/revisions"}],"wp:attachment":[{"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/media?parent=2605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/categories?post=2605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kizeoformscom.kinsta.cloud\/fr\/wp-json\/wp\/v2\/tags?post=2605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}